{"id":2424,"date":"2016-04-23T15:21:14","date_gmt":"2016-04-23T14:21:14","guid":{"rendered":"https:\/\/visegradpost.com\/?p=2424"},"modified":"2025-05-27T15:24:53","modified_gmt":"2025-05-27T14:24:53","slug":"comprendre-le-conflit-autour-du-tribunal-constitutionnel-polonais","status":"publish","type":"post","link":"https:\/\/visegradpost.com\/fr\/2016\/04\/23\/comprendre-le-conflit-autour-du-tribunal-constitutionnel-polonais\/","title":{"rendered":"Comprendre le conflit autour du Tribunal constitutionnel polonais"},"content":{"rendered":"<p>Pologne, Varsovie \u2013 Le 13 avril, le Parlement europ\u00e9en adoptait\u00a0<u>une r\u00e9solution<\/u>\u00a0demandant \u00e0 Varsovie de publier et appliquer\u00a0les r\u00e9solutions du Tribunal constitutionnel\u00a0polonais afin que\u00a0les principes d\u2019\u00c9tat de droit\u00a0soient respect\u00e9s conform\u00e9ment aux trait\u00e9s europ\u00e9ens.\u00a0Une r\u00e9solution vot\u00e9e\u00a0\u00e0 une large majorit\u00e9, avec les voix de l\u2019extr\u00eame-gauche, des socialistes, des lib\u00e9raux, des Verts et du PPE (sans les d\u00e9put\u00e9s Fidesz hongrois qui ont tous vot\u00e9 contre). Dans leur texte, les d\u00e9put\u00e9s europ\u00e9ens se r\u00e9f\u00e8rent \u00e0 l\u2019avis de la Commission de Venise du 12 mars 2016 concernant les amendements du 22\u00a0d\u00e9cembre\u00a02015 \u00e0 la loi du 25\u00a0juin\u00a02015 sur le Tribunal constitutionnel de la Pologne. Un avis demand\u00e9 par le gouvernement polonais lui-m\u00eame et qui est plus nuanc\u00e9 que la r\u00e9solution du Parlement europ\u00e9en du 13 avril, puisqu\u2019il reconna\u00eet que la crise actuelle remonte aux agissements de la majorit\u00e9 pr\u00e9c\u00e9dente en mai-juin 2015 et que cette crise ayant une origine politique, la solution devra aussi \u00eatre politique.<\/p>\n<p>Rappelons aussi que, sur la question de son Tribunal constitutionnel, la Pologne fait l\u2019objet d\u2019un \u00ab\u00a0dialogue structur\u00e9\u00a0\u00bb lanc\u00e9 par la Commission europ\u00e9enne pour s\u2019assurer du respect de l\u2019\u00c9tat de droit, et que cette m\u00eame Commission avait demand\u00e9 au parlement polonais de suspendre ses travaux sur la r\u00e9forme de sa loi du 25 juin 2015 sur le Tribunal constitutionnel. Le Parlement polonais n\u2019a bien entendu pas obtemp\u00e9r\u00e9.<\/p>\n<p>Il est d\u2019ailleurs regrettable que la m\u00eame Commission n\u2019ait pas fait preuve du m\u00eame z\u00e8le en mai-juin 2015 quand la majorit\u00e9 pr\u00e9c\u00e9dente, form\u00e9e par les lib\u00e9raux de la Plateforme civique (PO) et le parti \u00ab\u00a0paysan\u00a0\u00bb (PSL), prenant conscience de sa d\u00e9faite tr\u00e8s probable aux \u00e9lections parlementaires du 25 octobre 2015, avait vot\u00e9 une loi sp\u00e9ciale pour l\u2019occasion. Une loi pr\u00e9par\u00e9e avec l\u2019aide du pr\u00e9sident et de deux juges du Tribunal constitutionnel, et qui a permis \u00e0 la majorit\u00e9 sortante de remplacer \u00e0 l\u2019avance, le 8 octobre 2015, sur les quinze juges que compte le Tribunal, trois juges dont les mandats expiraient le 6 novembre et deux juges dont les mandats devaient s\u2019\u00e9teindre respectivement le 2 et le 8 d\u00e9cembre. Ceci aurait verrouill\u00e9 pour longtemps le Tribunal constitutionnel d\u00e9j\u00e0 largement domin\u00e9 par des proches de l\u2019ancienne majorit\u00e9 et dont le pr\u00e9sident, Andrzej\u00a0Rzepli\u0144ski, avait m\u00eame \u00e9t\u00e9 pressenti comme ministre de la Justice du gouvernement PO-PSL avant d\u2019\u00eatre nomm\u00e9 au Tribunal constitutionnel.<\/p>\n<p>Le pr\u00e9sident de la R\u00e9publique polonaise Andrzej Duda a refus\u00e9 d\u2019assermenter ces juges, jugeant leur nomination contraire \u00e0 la Constitution, puisque le parlement sortant s\u2019\u00e9tait arrog\u00e9 un droit de nomination des juges qui aurait d\u00fb revenir au nouveau parlement.<\/p>\n<p>Le 25 novembre, la nouvelle majorit\u00e9 du parti conservateur Droit et Justice (PiS), appuy\u00e9e par le parti d\u2019opposition Kukiz\u201915, a d\u00e9clar\u00e9 nulles les r\u00e9solutions du 8 octobre portant nomination des cinq nouveaux juges. L\u2019opposition PO, \u00e0 l\u2019origine du conflit, a alors port\u00e9 sa propre loi de juin devant le Tribunal constitutionnel. Le 2 d\u00e9cembre la Di\u00e8te polonaise (la chambre basse du parlement, qui est comp\u00e9tente pour le choix des juges) a nomm\u00e9 cinq nouveaux juges que le pr\u00e9sident Duda a asserment\u00e9s. Le pr\u00e9sident du Tribunal constitutionnel leur a affect\u00e9 des bureaux, mais il a en m\u00eame temps d\u00e9cid\u00e9 qu\u2019il ne leur confierait aucune affaire tant que la l\u00e9galit\u00e9 de leur nomination n\u2019aurait pas \u00e9t\u00e9 confirm\u00e9e.<\/p>\n<p>Dans un jugement rendu le 3 d\u00e9cembre, le Tribunal constitutionnel a ensuite affirm\u00e9 que la loi de juin violait effectivement la constitution, mais uniquement en ce qui concerne la nomination anticip\u00e9e des juges dont le mandat devait prendre effet en d\u00e9cembre. Pour le Tribunal constitutionnel, les nominations en remplacement des trois juges dont le mandat arrivait \u00e0 terme d\u00e9but novembre \u00e9taient, elles, conformes \u00e0 la constitution. Pour la majorit\u00e9 parlementaire, n\u00e9anmoins, le Tribunal constitutionnel n\u2019est pas habilit\u00e9 par la Constitution polonaise \u00e0 se prononcer sur la validit\u00e9 des nominations des juges faites par le Parlement, puisque la Di\u00e8te a une comp\u00e9tence exclusive en la mati\u00e8re et qu\u2019elle le fait en adoptant des r\u00e9solutions (tandis que le Tribunal constitutionnel n\u2019est habilit\u00e9 \u00e0 statuer que sur la constitutionnalit\u00e9 des lois).<\/p>\n<p>Depuis, le pr\u00e9sident Rzepli\u0144ski, dont le mandat doit durer jusqu\u2019en d\u00e9cembre prochain, refuse de\u00a0confier des affaires\u00a0\u00e0 trois des cinq juges nomm\u00e9s par la nouvelle majorit\u00e9 parlementaire. Une majorit\u00e9 qui reproche \u00e0 Rzepli\u0144ski\u00a0son engagement politique et son manque \u00e0 son\u00a0devoir de r\u00e9serve\u00a0dans les m\u00e9dias, et aussi son implication dans la pr\u00e9paration de la loi de juin 2015 que le Tribunal constitutionnel a ensuite reconnue comme \u00e9tant partiellement inconstitutionnelle.<\/p>\n<p>Pour r\u00e9soudre le conflit \u00e0 son profit, la majorit\u00e9 PiS a donc vot\u00e9 le 22 d\u00e9cembre un amendement \u00e0 la loi du 25 juin sur le Tribunal constitutionnel. La constitution polonaise indique que c\u2019est le parlement qui d\u00e9finit les modalit\u00e9s de fonctionnement du Tribunal constitutionnel \u00e0 la majorit\u00e9 simple et c\u2019est donc ce que la majorit\u00e9 parlementaire a fait.<\/p>\n<p>Quels sont donc les changements apport\u00e9s \u00e0 la loi polonaise qui, selon leurs d\u00e9tracteurs, vont instaurer une \u00ab\u00a0dictature\u00a0\u00bb de la majorit\u00e9 parlementaire en Pologne en bloquant de fait le fonctionnement du Tribunal constitutionnel\u00a0? Selon les nouvelles dispositions, le Tribunal constitutionnel doit examiner les recours contre les lois vot\u00e9es par le Parlement au complet, c\u2019est-\u00e0-dire \u00e0 treize juges au moins (sur quinze), et non plus en comit\u00e9 restreint de quelques juges choisis par le pr\u00e9sident de la Cour Andrzej Rzepli\u0144ski, sans doute un peu en fonction de la d\u00e9cision d\u00e9sir\u00e9e. Deuxi\u00e8me changement majeur, les recours doivent \u00eatre examin\u00e9s dans l\u2019ordre de leur r\u00e9ception par la Cour constitutionnelle et non plus dans l\u2019ordre d\u00e9cid\u00e9 par ce m\u00eame pr\u00e9sident de la Cour qui est une fois de plus accus\u00e9 d\u2019avoir utilis\u00e9 ces derni\u00e8res ann\u00e9es cette pr\u00e9rogative pour soutenir son ancien parti. Les recours g\u00eanants pouvaient attendre plusieurs ann\u00e9es tandis que ceux qui \u00e9taient d\u00e9sir\u00e9s par le gouvernement pr\u00e9c\u00e9dent pouvaient \u00eatre examin\u00e9s quasiment imm\u00e9diatement. Le troisi\u00e8me changement concerne la destitution d\u2019un juge de la Cour constitutionnelle pour faute grave ou incapacit\u00e9. Jusqu\u2019ici la Cour elle-m\u00eame \u00e9tait seule comp\u00e9tente. D\u00e9sormais, si c\u2019est toujours elle qui prend la d\u00e9cision de destituer un de ses juges, sa d\u00e9cision doit \u00eatre approuv\u00e9e par la Di\u00e8te. Par ailleurs, le pr\u00e9sident de la R\u00e9publique et le ministre de la Justice peuvent eux aussi prendre l\u2019initiative d\u2019une telle destitution m\u00eame si la d\u00e9cision elle-m\u00eame reste du ressort de la Cour constitutionnelle.<\/p>\n<p>Seulement voil\u00e0, le 9 mars 2016 le Tribunal constitutionnel s\u2019est r\u00e9uni \u00e0 douze juges (sans les trois juges litigieux) pour se prononcer sur la constitutionnalit\u00e9 de ces amendements \u00e0 la loi le concernant. Autant dire que le Tribunal \u00e9tait \u00e0 la fois juge et parti, et son jugement\u00a0a en plus fuit\u00e9 dans les m\u00e9dias\u00a0avant m\u00eame d\u2019\u00eatre rendu. Il y a eu des accusations de\u00a0consultation pr\u00e9alable\u00a0du jugement entre les juges \u00ab\u00a0PO\u00a0\u00bb du Tribunal constitutionnel et les d\u00e9put\u00e9s PO de la Di\u00e8te, sans que cela puisse toutefois \u00eatre prouv\u00e9. Toujours est-il que le 9 mars le Tribunal constitutionnel a consid\u00e9r\u00e9 que les amendements du 22 d\u00e9cembre \u00e9taient inconstitutionnels et que c\u2019est donc toujours la loi du 25 juin 2015 qui s\u2019applique. Mais comme il s\u2019est r\u00e9uni sans respecter la loi (telle que modifi\u00e9e le 22 d\u00e9cembre) r\u00e9glementant son fonctionnement (il s\u2019est r\u00e9uni \u00e0 douze juges au lieu du minimum exig\u00e9 de treize et il n\u2019a pas respect\u00e9 l\u2019ordre d\u2019arriv\u00e9e des recours \u00e0 examiner), le gouvernement de Beata\u00a0Szyd\u0142o\u00a0a refus\u00e9 de publier ce jugement. Car pour la majorit\u00e9 PiS et une partie des experts en\u00a0droit constitutionnel\u00a0qui s\u2019expriment dans les m\u00e9dias, on n\u2019a pas ici affaire \u00e0 un jugement mais \u00e0 un simple avis juridique rendu par une partie des juges du Tribunal constitutionnel. Bien entendu, la majeure partie de l\u2019opposition et d\u2019autres experts en droit constitutionnel sont d\u2019un avis tout \u00e0 fait contraire et consid\u00e8rent que c\u2019est le gouvernement qui viole la constitution en refusant de publier ce qu\u2019ils consid\u00e8rent, eux, comme un jugement.<\/p>\n<p>Le conflit est en fait inextricable sur le plan juridique, et c\u2019est pourquoi la Commission de Venise a eu raison de souligner la n\u00e9cessit\u00e9 d\u2019un accord politique entre la majorit\u00e9 et l\u2019opposition. Mais ce n\u2019est qu\u2019\u00e0 Varsovie qu\u2019une issue peut \u00eatre trouv\u00e9e, \u00e0 condition que les grandes forces politiques, y compris le PiS, trouvent le moyen de modifier ensemble la loi sur le Tribunal constitutionnel et aussi la constitution polonaise, afin qu\u2019une telle situation ne puisse pas se reproduire. Des discussions sont en cours, mais les accusations mutuelles continuent de fuser dans les m\u00e9dias, ce qui ne favorise pas un compromis.<\/p>\n<p>Les\u00a0interventions partiales\u00a0et mal inform\u00e9es de Bruxelles, survenant \u00e0 la demande de membres du parti PO qui sont au minimum coresponsables de la crise et dont\u00a0la mauvaise foi\u00a0saute aux yeux dans cette affaire, ne peuvent qu\u2019envenimer les choses et risquent aussi de rendre la droite conservatrice polonaise, majoritaire, encore plus eurosceptique qu\u2019elle ne l\u2019est d\u00e9j\u00e0 devenue apr\u00e8s la crise de l\u2019euro, les attaques de Bruxelles contre la Hongrie depuis 2010 et la crise migratoire actuelle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pologne, Varsovie \u2013 Le 13 avril, le Parlement europ\u00e9en adoptait\u00a0une r\u00e9solution\u00a0demandant \u00e0 Varsovie de publier et appliquer\u00a0les r\u00e9solutions du Tribunal constitutionnel\u00a0polonais afin que\u00a0les principes d\u2019\u00c9tat de droit\u00a0soient respect\u00e9s conform\u00e9ment aux trait\u00e9s europ\u00e9ens.\u00a0Une r\u00e9solution vot\u00e9e\u00a0\u00e0 une large majorit\u00e9, avec les voix de l\u2019extr\u00eame-gauche, des socialistes, des lib\u00e9raux, des Verts et du PPE (sans les d\u00e9put\u00e9s Fidesz<\/p>","protected":false},"author":5,"featured_media":2425,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-2424","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actu"],"_links":{"self":[{"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/posts\/2424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/comments?post=2424"}],"version-history":[{"count":0,"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/posts\/2424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/media\/2425"}],"wp:attachment":[{"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/media?parent=2424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/categories?post=2424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visegradpost.com\/fr\/wp-json\/wp\/v2\/tags?post=2424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}